{"id":19262,"date":"2025-06-05T16:00:30","date_gmt":"2025-06-05T14:00:30","guid":{"rendered":"https:\/\/www.tibethaus.com\/?post_type=tribe_events&#038;p=19262"},"modified":"2025-06-05T16:00:30","modified_gmt":"2025-06-05T14:00:30","slug":"einfach-sein-retreat","status":"publish","type":"tribe_events","link":"https:\/\/www.tibethaus.com\/zh-hans\/event\/einfach-sein-retreat\/","title":{"rendered":"Einfach Sein \u2013 In der Gegenw\u00e4rtigkeit Freiheit finden \u2212 Praxisretreat rb"},"content":{"rendered":"<p class=\"p1\">Retreatleitung | <i>Birgit Justl und Martin Br\u00fcger <\/i><\/p>\n<p><span data-contrast=\"auto\">Dieses <\/span><span data-contrast=\"auto\">Retreat <\/span><span data-contrast=\"auto\">ist eine wunderbare Gelegenheit, um f\u00fcr ein paar Tage unseren Alltag pausieren zu lassen und im sch\u00f6n gelegenen Retreathaus Berghof zu meditieren.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Wir wollen zusammen eine radikale spirituelle Redlichkeit erforschen. Was f\u00fchrt uns zur Befreiung aus unserem leidhaften und get\u00e4uschten Zustand? Eine Praxis die sich in der Zukunft auswirken wird? Aber erreichen wir jemals die Zukunft? Dem wollen wir eine Meditationspraxis gegen\u00fcberstellen, die einzig auf die tiefe Erfahrung der Gegenwart ausgerichtet ist, in der wir frei von irgendwelchen Erwartungen ruhen und zu erkennen versuchen, dass die konzepthaften, in Vergangenheit und Zukunft st\u00f6bernden, mit weltlichen und spirituellen Illusionen besch\u00e4ftigten, geistigen Aktivit\u00e4ten uns davor abhalten, im gegenw\u00e4rtigen Moment Befreiung zu finden. Durch v\u00f6lliges Loslassen dessen, was im Moment nicht ist und durch ausnahmslose Akzeptanz dessen, was im Moment ist, k\u00f6nnen wir erkennen, dass Perfektion (unsere Buddhanatur) und Befreiung schon immer in uns ist und sofort erbl\u00fcht, sobald wir nicht mehr nach einem Zustand streben, der anders ist als das was gerade ist.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Wir werden den Kurs zum Teil schweigend verbringen und sechs Stunden am Tag meditieren. Die Teilnehmenden sollten deshalb etwas Meditationserfahrung haben.\u202fDurch das gemeinsame Zubereiten der veganen Mahlzeiten \u00fcben wir Achtsamkeit und Gegenw\u00e4rtigkeit im Alltag, unsere formale Praxis auf dem Kissen erg\u00e4nzen wir durch Hatha-Yoga.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Martin Br\u00fcger<\/span><\/b><span data-contrast=\"auto\">, Bildender K\u00fcnstler, langj\u00e4hriger Praktizierender, Dharma-Tutor, Manager des Tibethaus Shop.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Birgit Justl<\/span><\/b><span data-contrast=\"auto\">, Dipl.-Betriebswirtin, Dipl.-Psychologin, Psychoanalytikerin, Dharma-Tutorin.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p class=\"p1\">Anmeldeschluss ist zwei Wochen vorher.<\/p>\n<p class=\"p2\"><b>Zeit | Mittwoch 18 Uhr bis Sonntag 15 Uhr <\/b><b><\/b><\/p>\n<p class=\"p1\"><i>Regul\u00e4r 250 Euro | Mitglieder 175 Euro | Erm\u00e4\u00dfigt 125 Euro <\/i><i>(zzgl. Kost und Logis) <\/i><i><\/i><\/p>\n<p class=\"p1\"><b>Bitte direkt anmelden \u00fcber: <\/b><b><\/b><\/p>\n<p class=\"p1\"><a href=\"https:\/\/www.retreathaus-berghof.de\/anmeldung\"><i>https:\/\/www.retreathaus-berghof.de\/anmeldung<\/i><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retreatleitung | Birgit Justl und Martin Br\u00fcger<\/p>\n<p>Wir wollen Meditationen erforschen, die auf die tiefe Erfahrung der Gegenwart gerichtet sind, frei von Erwartungen und erkennend, dass unsere konzepthaften, illusion\u00e4ren geistigen Aktivit\u00e4ten uns davor abhalten, Befreiung zu finden. Durch v\u00f6lliges Loslassen dessen, was im Moment nicht ist und durch v\u00f6llige Akzeptanz dessen, was ist, er- kennen wir, dass unsere Buddhanatur und Befreiung schon immer in uns sind. Wir werden den Kurs zum Teil schweigend verbringen. Die Teilnehmenden sollten etwas Meditationserfahrung haben. Durch das gemeinsame Zubereiten der veganen Mahlzeiten \u00fcben wir Gegenw\u00e4rtigkeit im Alltag, unsere Praxis auf dem Kissen erg\u00e4nzen wir durch Hatha-Yoga. Anmeldeschluss ist zwei Wochen vorher.<\/p>\n","protected":false},"author":5,"featured_media":19505,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[180,680,179,119,359],"tribe_events_cat":[38],"class_list":["post-19262","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-birgit-justl","tag-einfach-sein","tag-martin-brueger","tag-retreat","tag-retreathaus-berghof","tribe_events_cat-buddhismus","cat_buddhismus"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events\/19262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":2,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events\/19262\/revisions"}],"predecessor-version":[{"id":19509,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events\/19262\/revisions\/19509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/media\/19505"}],"wp:attachment":[{"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=19262"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tags?post=19262"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events_cat?post=19262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}