{"id":10000604,"date":"2025-03-21T10:52:32","date_gmt":"2025-03-21T09:52:32","guid":{"rendered":"https:\/\/www.tibethaus.com\/?post_type=tribe_events&#038;p=17741"},"modified":"2025-11-13T17:17:46","modified_gmt":"2025-11-13T16:17:46","slug":"meditation-fuer-junge-leute-reihe-4","status":"publish","type":"tribe_events","link":"https:\/\/www.tibethaus.com\/zh-hans\/event\/meditation-fuer-junge-leute-reihe-4\/2025-11-04\/","title":{"rendered":"Offene Meditation f\u00fcr Junge Leute"},"content":{"rendered":"<div id=\"elementor-tab-title-1032\" class=\"elementor-tab-title elementor-active\" tabindex=\"0\" role=\"button\" data-tab=\"2\" aria-controls=\"elementor-tab-content-1032\" aria-expanded=\"true\" aria-selected=\"true\"><span style=\"font-family: -apple-system, system-ui, BlinkMacSystemFont, 'Segoe UI', Helvetica, Arial, sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol';\">Leitung | Alex Arsoudis<\/span><\/div>\n<div id=\"elementor-tab-content-1032\" class=\"elementor-tab-content elementor-clearfix elementor-active\" role=\"region\" data-tab=\"2\" aria-labelledby=\"elementor-tab-title-1032\">\n<div><\/div>\n<div>Viele Menschen denken, dass (intensive) spirituelle Praxis etwas f\u00fcr das Alter ist, wenn der Tod naht, die normalen Lebensprojekte abgeschlossen sind. Der Buddha hat jedoch durch sein eigenes Beispiel gezeigt, dass die einzige Zeit immer \u201cjetzt\u201d ist, wann auch immer dieses \u201cjetzt\u201d sein mag. Diese Gruppe richtet sich vor allem an j\u00fcngere Personen, um einen Raum f\u00fcr Gleichgesinnte zu schaffen, aber jeder ist nat\u00fcrlich willkommen.<\/div>\n<div><\/div>\n<div>Anmeldung und Vorkenntnisse sind nicht erforderlich. Interessierte sind jederzeit willkommen.<\/div>\n<div><\/div>\n<div class=\"elementToProof\"><b>Zeit<\/b> | 19.30 bis 21 Uhr<\/div>\n<div><\/div>\n<div>\n<p class=\"p2\">In den Tibethaus-Ferien und an Feiertagen findet die Meditation nicht statt.<\/p>\n<p>Die Teilnahme ist geb\u00fchrenfrei; wir freuen uns \u00fcber eine\u00a0<a href=\"https:\/\/www.tibethaus.com\/mitmachen\/spenden\/\">Spende f\u00fcr den Buddhismus-Bereich.<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Leitung | Alex Arsoudis<\/p>\n<p>Viele Menschen denken, dass (intensive) spirituelle Praxis etwas f\u00fcr das Alter ist, wenn der Tod naht, die normalen Lebensprojekte abgeschlossen sind. Der Buddha hat jedoch durch sein eigenes Beispiel gezeigt, dass die einzige Zeit immer \u201cjetzt\u201d ist, wann auch immer dieses \u201cjetzt\u201d sein mag. Diese Gruppe richtet sich vor allem an j\u00fcngere Personen, um einen Raum f\u00fcr Gleichgesinnte zu schaffen, aber jeder ist nat\u00fcrlich willkommen.<\/p>\n","protected":false},"author":5,"featured_media":14600,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[534,118,533],"tribe_events_cat":[38],"class_list":["post-10000604","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-alex-arsoudis","tag-meditation","tag-woechentliche-meditation","tribe_events_cat-buddhismus","cat_buddhismus","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events\/10000604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":0,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events\/10000604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/media\/14600"}],"wp:attachment":[{"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=10000604"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tags?post=10000604"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.tibethaus.com\/zh-hans\/wp-json\/wp\/v2\/tribe_events_cat?post=10000604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}