{"id":27334,"date":"2026-05-29T14:42:21","date_gmt":"2026-05-29T12:42:21","guid":{"rendered":"https:\/\/www.tibethaus.com\/?post_type=tribe_events&#038;p=27334"},"modified":"2026-06-01T13:07:41","modified_gmt":"2026-06-01T11:07:41","slug":"hatha-yoga-kurs-einsteiger-vor-ort-beginn-2","status":"publish","type":"tribe_events","link":"https:\/\/www.tibethaus.com\/tb\/event\/hatha-yoga-kurs-einsteiger-vor-ort-beginn-2\/","title":{"rendered":"Hatha-Yoga-Kurs (Einsteiger) (vor Ort) (Beginn)"},"content":{"rendered":"<p>DIENSTAG 15. SEPTEMBER BIS 8. DEZEMBER 2026<\/p>\n<p class=\"p1\">Leitung | <i>Claudia Rauer <\/i><i><\/i><\/p>\n<p class=\"p1\">Behutsame Einf\u00fchrung in einfache Yoga-\u00dcbungen und harmonische \u00dcbungsabl\u00e4ufe, die zu mehr Flexibilit\u00e4t und Gelassenheit f\u00fchren. Der Kurs ist f\u00fcr Anf\u00e4nger\/innen mit und ohne Yoga-Erfahrung sowie f\u00fcr Senior\/innen geeignet und als Pr\u00e4ventionskurs zertifiziert (anteilige Erstattung von gesetzlichen Krankenkassen).<\/p>\n<p class=\"p1\">Anmeldeschluss ist eine Woche vorher.<\/p>\n<p class=\"p2\"><b>Zeit | 18 bis 19.30 Uhr, <\/b><span class=\"s2\">max. 12 Teilnehmende <\/span><\/p>\n<p class=\"p1\"><i>Regul\u00e4r 175 Euro | Mitglieder 105 Euro <\/i><i><\/i><\/p>\n<p class=\"p2\"><b>Hatha-Yoga-Kurs <\/b><span class=\"s2\"><b>(Einsteiger) <\/b><b><\/b><\/span>Findet nicht am 5., 12. und 19.10.2026 Oktober statt.<\/p>\n<p class=\"p1\"><b>Unsere Kursgeb\u00fchren folgen dem Gedanken der gegenseitigen Unterst\u00fctzung:<\/b><br \/>\nManche tragen mehr, damit andere weniger zahlen k\u00f6nnen \u2013 und gemeinsam erm\u00f6glichen wir so ein offenes, vielf\u00e4ltiges Miteinander. Der regul\u00e4re Beitrag\u00a0hilft, das Tibethaus auf eine stabile Grundlage zu stellen und gleichzeitig Teilhabe f\u00fcr alle zu schaffen. \u00a0Ein kleiner Beitrag mit gro\u00dfer Wirkung \u2013 herzlichen Dank f\u00fcr eure Solidarit\u00e4t und Verbundenheit.<\/p>\n<p class=\"p3\"><b>Erm\u00e4\u00dfigte Kursgeb\u00fchren<\/b><b><\/b><\/p>\n<p class=\"p3\">Unsere erm\u00e4\u00dfigten Geb\u00fchren richten sich an Menschen mit geringeren finanziellen M\u00f6glichkeiten \u2013 zum Beispiel Sch\u00fcler\/innen, Student\/innen, Auszubildende, Erwerbslose oder Rentner\/innen mit kleiner Rente. Wir vertrauen darauf, dass jede und jeder die passende Geb\u00fchr nach den eigenen M\u00f6glichkeiten w\u00e4hlt. In Einzelf\u00e4llen k\u00f6nnen wir um einen Nachweis bitten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIENSTAG 15. SEPTEMBER BIS 8. DEZEMBER 2026<\/p>\n<p>Leitung | Claudia Rauer<\/p>\n<p>Behutsame Einf\u00fchrung in einfache Yoga-\u00dcbungen und harmonische \u00dcbungsabl\u00e4ufe, die zu mehr Flexibilit\u00e4t und Gelassenheit f\u00fchren. Der Kurs ist f\u00fcr Anf\u00e4nger\/innen mit und ohne Yoga-Erfahrung sowie f\u00fcr Senior\/innen geeignet und als Pr\u00e4ventionskurs zertifiziert (anteilige Erstattung von gesetzlichen Krankenkassen).<\/p>\n","protected":false},"author":5,"featured_media":14299,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[{\"id\":27335,\"type\":\"default\",\"title\":\"26-09-15-CR_Hatha-Yoga-Einsteiger-Regul\\u00e4r\",\"description\":\"\",\"capacityType\":\"unlimited\",\"price\":175,\"capacity\":\"\",\"available\":-1,\"sharedCapacity\":\"\",\"sold\":0,\"shareSold\":0,\"isShared\":true,\"currencyDecimalPoint\":\",\",\"currencyNumberOfDecimals\":2,\"currencyPosition\":\"postfix\",\"currencySymbol\":\"\\u20ac\",\"currencyThousandsSep\":\".\"},{\"id\":27336,\"type\":\"default\",\"title\":\"26-09-15-CR_Hatha-Yoga-Einsteiger-MItglieder\",\"description\":\"\",\"capacityType\":\"unlimited\",\"price\":105,\"capacity\":\"\",\"available\":-1,\"sharedCapacity\":\"\",\"sold\":0,\"shareSold\":0,\"isShared\":true,\"currencyDecimalPoint\":\",\",\"currencyNumberOfDecimals\":2,\"currencyPosition\":\"postfix\",\"currencySymbol\":\"\\u20ac\",\"currencyThousandsSep\":\".\"}]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[101,418,100,102],"tribe_events_cat":[41],"class_list":["post-27334","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-claudia-rauer","tag-hatha-yoga","tag-yoga","tag-yoga-einsteiger","tribe_events_cat-heilkunde","cat_heilkunde"],"acf":[],"ticketed":["woo"],"_links":{"self":[{"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/tribe_events\/27334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/tribe_events\/27334\/revisions"}],"predecessor-version":[{"id":27337,"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/tribe_events\/27334\/revisions\/27337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/media\/14299"}],"wp:attachment":[{"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/media?parent=27334"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/tags?post=27334"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.tibethaus.com\/tb\/wp-json\/wp\/v2\/tribe_events_cat?post=27334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}