{"id":28094,"date":"2026-06-12T09:49:05","date_gmt":"2026-06-12T07:49:05","guid":{"rendered":"https:\/\/www.tibethaus.com\/?post_type=tribe_events&#038;p=28094"},"modified":"2026-06-12T09:49:05","modified_gmt":"2026-06-12T07:49:05","slug":"puja-dez-1","status":"publish","type":"tribe_events","link":"https:\/\/www.tibethaus.com\/en\/event\/puja-dez-1\/","title":{"rendered":"Medizinbuddha Puja mit Shenphen Rinpoche (in tibetischer Sprache)"},"content":{"rendered":"<p class=\"p2\">Shenphen Rinpoche wird einmal im Monat im Wechsel die Praxis der Gr\u00fcnen Tara sowie die Medizinbuddha-Praxis durchf\u00fchren.<\/p>\n<p class=\"p2\">Die Rezitation findet auf Tibetisch statt.<\/p>\n<p class=\"p2\">Anmeldung ist nicht erforderlich, alle Interessierten sind willkommen.<\/p>\n<p class=\"p1\"><b>Zeit | 18.30 bis 19.30 Uhr <\/b><b><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shenphen Rinpoche wird einmal im Monat im Wechsel die Praxis der Gr\u00fcnen Tara sowie die Medizinbuddha-Praxis durchf\u00fchren.<\/p>\n<p>Die Rezitation findet auf Tibetisch statt.<\/p>\n<p>Anmeldung ist nicht erforderlich, alle Interessierten sind willkommen.<\/p>\n","protected":false},"author":5,"featured_media":11908,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[923,578,109],"tribe_events_cat":[38],"class_list":["post-28094","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-medizinbuddha","tag-puja","tag-shenphen-rinpoche","tribe_events_cat-buddhismus","cat_buddhismus"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events\/28094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events\/28094\/revisions"}],"predecessor-version":[{"id":28103,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events\/28094\/revisions\/28103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/media\/11908"}],"wp:attachment":[{"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/media?parent=28094"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tags?post=28094"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=28094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}