{"id":19274,"date":"2025-06-05T16:08:56","date_gmt":"2025-06-05T14:08:56","guid":{"rendered":"https:\/\/www.tibethaus.com\/?post_type=tribe_events&#038;p=19274"},"modified":"2025-10-24T10:50:13","modified_gmt":"2025-10-24T08:50:13","slug":"verbinden-zuhoeren-veraendern-ein-kurs-in-achtsamer-kommunikation-beginn","status":"publish","type":"tribe_events","link":"https:\/\/www.tibethaus.com\/en\/event\/verbinden-zuhoeren-veraendern-ein-kurs-in-achtsamer-kommunikation-beginn\/","title":{"rendered":"Verbinden \u2013 zuh\u00f6ren \u2013 ver\u00e4ndern &#8211; Ein Kurs in achtsamer Kommunikation (Beginn)"},"content":{"rendered":"<p class=\"p1\">Kurs | <i>Heike Merkle <\/i><i><\/i><\/p>\n<p class=\"p1\">Kommunikation ist ein zentraler Bestandteil unseres Lebens. Doch wie oft reden wir aneinander vorbei, f\u00fchlen uns nicht geh\u00f6rt oder sind zu sehr mit unseren eigenen Gedanken besch\u00e4ftigt, um wirklich zuzuh\u00f6ren? In diesem Kurs erforschen wir gemeinsam, wie wir mit der Kraft der Achtsamkeit bewusster und offener miteinander kommunizieren k\u00f6nnen.<\/p>\n<p class=\"p1\"><b>Wirklich zuh\u00f6ren: <\/b>Pr\u00e4senz und Mitgef\u00fchl entwickeln, um andere besser zu verstehen.<\/p>\n<p class=\"p1\"><b>Klar ausdr\u00fccken: <\/b>Authentisch und respektvoll kommunizieren, was uns wichtig ist.<\/p>\n<p class=\"p1\"><b>Innere Muster erkennen: <\/b>Wie beeinflussen unsere Gedanken, Erwartungen und Emotionen unsere Gespr\u00e4che \u2013 und wie k\u00f6nnen wir uns davon l\u00f6sen? Der Kurs bietet Raum, mit praktischen \u00dcbungen und Reflexionen die eigene Kommunikationsweise zu hinterfragen und zu vertiefen. Er ist ideal f\u00fcr Menschen, die bereits an einem MBSR-Kurs teilgenommen haben oder eine eigene Achtsamkeitspraxis etabliert haben und diese erweitern m\u00f6chten.<\/p>\n<p class=\"p2\"><b>Zeit | 19 bis 21 Uhr <\/b><span class=\"s1\">(inkl. Pause) <\/span><\/p>\n<p class=\"p1\"><b>Folgende Termine sind vorgesehen: <\/b><i>30.10., 13.11., 27.11. und 11.12.2025 <\/i><i><\/i><\/p>\n<p class=\"p1\"><i>Regul\u00e4r 210 Euro | Mitglieder 170 Euro | Erm\u00e4\u00dfigt 170 Euro <\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kurs | Heike Merkle<\/p>\n<p>Kommunikation ist ein zentraler Bestandteil unseres Lebens. Doch wie oft reden wir aneinander vorbei, f\u00fchlen uns nicht geh\u00f6rt oder sind zu sehr mit unseren eigenen Gedanken besch\u00e4ftigt, um wirklich zuzuh\u00f6ren? In diesem Kurs erforschen wir gemeinsam, wie wir mit der Kraft der Achtsamkeit bewusster und offener miteinander kommunizieren k\u00f6nnen.<\/p>\n","protected":false},"author":5,"featured_media":12730,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"canceled","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[560,98],"tribe_events_cat":[39],"class_list":["post-19274","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-achtsame-kommunikation","tag-heike-merkle","tribe_events_cat-persoenlichkeit","cat_persoenlichkeit","tribe-events-status__list-event-canceled"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events\/19274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":3,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events\/19274\/revisions"}],"predecessor-version":[{"id":21993,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events\/19274\/revisions\/21993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/media\/12730"}],"wp:attachment":[{"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/media?parent=19274"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tags?post=19274"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.tibethaus.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=19274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}